{"id":4409,"date":"2023-07-05T20:11:58","date_gmt":"2023-07-05T18:11:58","guid":{"rendered":"https:\/\/ship-tracker.org\/?page_id=4409"},"modified":"2023-07-05T20:11:58","modified_gmt":"2023-07-05T18:11:58","slug":"skagen-maersk","status":"publish","type":"page","link":"https:\/\/ship-tracker.org\/fr\/skagen-maersk\/","title":{"rendered":"SKAGEN MAERSK"},"content":{"rendered":"<h2><span style=\"color: #000000;\">Emplacement actuel et <\/span><span style=\"color: #000000;\">position de SKAGEN MAERSK<\/span><\/h2>\n<p>O\u00f9 se trouve actuellement SKAGEN MAERSK ?<br \/>\n<script type=\"text\/javascript\">\n  var width=\"100%\";var height=\"400\";\n  var mmsi=219821000;\n<\/script><script type=\"text\/javascript\" src=\"https:\/\/www.vesselfinder.com\/aismap.js\"><\/script><br \/>\nLe SKAGEN MAERSKC, un cargo immatricul\u00e9 sous pavillon danois, navigue actuellement sur les mers. Le navire, portant le num\u00e9ro OMI 9166792 et le num\u00e9ro MMSI 219821000, mesure 347 m\u00e8tres de longueur et 43 m\u00e8tres de large. Les cartes fournies ci-dessous d\u00e9taillent les informations pertinentes sur le voyage, notamment l&#039;emplacement actuel du navire, son prochain port d&#039;escale pr\u00e9vu, l&#039;heure d&#039;arriv\u00e9e estim\u00e9e (ETA), l&#039;heure d&#039;arriv\u00e9e pr\u00e9vue (PTA), la vitesse, le cap et le tirant d&#039;eau. Des ressources suppl\u00e9mentaires telles que des photos, des vid\u00e9os, l&#039;heure locale et l&#039;heure UTC sont \u00e9galement fournies.<\/p>\n<h2 class=\"pageTitle shipItemTitle\"><span style=\"color: #000000;\">Examen et sp\u00e9cifications du SKAGEN MAERSK<\/span><\/h2>\n<table>\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">\u00c9tat du pavillon<\/td>\n<td style=\"width: 192px; height: 23px;\">Danemark<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Ann\u00e9e de construction<strong><br \/>\n<\/strong><\/td>\n<td style=\"width: 192px; height: 23px;\">1999<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Type de navire<\/td>\n<td style=\"width: 192px; height: 23px;\">Porte-conteneurs<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Signe d&#039;appel<\/td>\n<td style=\"width: 192px; height: 23px;\">OYOS2<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Jauge brute<\/td>\n<td style=\"width: 192px; height: 23px;\">92198<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Poids mort d&#039;\u00e9t\u00e9<\/td>\n<td style=\"width: 192px; height: 23px;\">110387<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Longueur<\/td>\n<td style=\"width: 192px; height: 23px;\"><span class=\"specificationUnit\">347 m<\/span><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Faisceau<\/td>\n<td style=\"width: 192px; height: 23px;\"><span class=\"specificationUnit\">43 m<\/span><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">OMI<\/td>\n<td style=\"width: 192px; height: 23px;\">9166792<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">MMSI<\/td>\n<td style=\"width: 192px; height: 23px;\">219821000<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 192px; height: 23px;\">Propri\u00e9taire<\/td>\n<td style=\"width: 192px; height: 23px;\"><a href=\"https:\/\/ship-tracker.org\/fr\/maersk\/\">Maersk<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Position actuelle du SKAGEN MAERSK\u00a0: O\u00f9 se trouve actuellement le SKAGEN MAERSK\u00a0? Le SKAGEN MAERSKC, un cargo battant pavillon danois, navigue actuellement en mer. Ce navire, immatricul\u00e9 sous le num\u00e9ro IMO 9166792 et le num\u00e9ro MMSI 219821000, mesure 347 m\u00e8tres de long et 43 m\u00e8tres de large. Les cartes\u2026&nbsp;<a href=\"https:\/\/ship-tracker.org\/fr\/skagen-maersk\/\" rel=\"bookmark\">En savoir plus &quot;<span class=\"screen-reader-text\">SKAGEN MAERSK<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":3637,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"class_list":["post-4409","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SKAGEN MAERSK\u2503Current location and position (cargo ship)<\/title>\n<meta name=\"description\" content=\"SKAGEN MAERSK \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ship-tracker.org\/fr\/skagen-maersk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SKAGEN MAERSK\u2503Current location and position (cargo ship)\" \/>\n<meta property=\"og:description\" content=\"SKAGEN MAERSK \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ship-tracker.org\/fr\/skagen-maersk\/\" \/>\n<meta property=\"og:site_name\" content=\"Ship-tracker.org\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/\",\"url\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/\",\"name\":\"SKAGEN MAERSK\u2503Current location and position (cargo ship)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ship-tracker.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/maersk-tanjong-g275700498_640.jpg\",\"datePublished\":\"2023-07-05T18:11:58+00:00\",\"description\":\"SKAGEN MAERSK \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ship-tracker.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/maersk-tanjong-g275700498_640.jpg\",\"contentUrl\":\"https:\\\/\\\/ship-tracker.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/maersk-tanjong-g275700498_640.jpg\",\"width\":640,\"height\":446,\"caption\":\"MAERSK ABERDEEN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/skagen-maersk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ship-tracker.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SKAGEN MAERSK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/#website\",\"url\":\"https:\\\/\\\/ship-tracker.org\\\/\",\"name\":\"Ship-tracker.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ship-tracker.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SKAGEN MAERSK\u2503Emplacement et position actuels (cargo)","description":"SKAGEN MAERSK \u2693 Emplacement et position actuels du navire MAERSK \u2713 Suivi des conteneurs Maersk \u2713 Live Ship Tracker \u2713 Porte-conteneurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ship-tracker.org\/fr\/skagen-maersk\/","og_locale":"fr_FR","og_type":"article","og_title":"SKAGEN MAERSK\u2503Current location and position (cargo ship)","og_description":"SKAGEN MAERSK \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship","og_url":"https:\/\/ship-tracker.org\/fr\/skagen-maersk\/","og_site_name":"Ship-tracker.org","og_image":[{"width":640,"height":446,"url":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ship-tracker.org\/skagen-maersk\/","url":"https:\/\/ship-tracker.org\/skagen-maersk\/","name":"SKAGEN MAERSK\u2503Emplacement et position actuels (cargo)","isPartOf":{"@id":"https:\/\/ship-tracker.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ship-tracker.org\/skagen-maersk\/#primaryimage"},"image":{"@id":"https:\/\/ship-tracker.org\/skagen-maersk\/#primaryimage"},"thumbnailUrl":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","datePublished":"2023-07-05T18:11:58+00:00","description":"SKAGEN MAERSK \u2693 Emplacement et position actuels du navire MAERSK \u2713 Suivi des conteneurs Maersk \u2713 Live Ship Tracker \u2713 Porte-conteneurs","breadcrumb":{"@id":"https:\/\/ship-tracker.org\/skagen-maersk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ship-tracker.org\/skagen-maersk\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ship-tracker.org\/skagen-maersk\/#primaryimage","url":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","contentUrl":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","width":640,"height":446,"caption":"MAERSK ABERDEEN"},{"@type":"BreadcrumbList","@id":"https:\/\/ship-tracker.org\/skagen-maersk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ship-tracker.org\/"},{"@type":"ListItem","position":2,"name":"SKAGEN MAERSK"}]},{"@type":"WebSite","@id":"https:\/\/ship-tracker.org\/#website","url":"https:\/\/ship-tracker.org\/","name":"Ship-tracker.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ship-tracker.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/pages\/4409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/comments?post=4409"}],"version-history":[{"count":1,"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/pages\/4409\/revisions"}],"predecessor-version":[{"id":4410,"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/pages\/4409\/revisions\/4410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/media\/3637"}],"wp:attachment":[{"href":"https:\/\/ship-tracker.org\/fr\/wp-json\/wp\/v2\/media?parent=4409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}