{"id":3948,"date":"2023-06-21T17:09:55","date_gmt":"2023-06-21T15:09:55","guid":{"rendered":"https:\/\/ship-tracker.org\/?page_id=3948"},"modified":"2023-06-21T17:09:55","modified_gmt":"2023-06-21T15:09:55","slug":"maersk-lavras","status":"publish","type":"page","link":"https:\/\/ship-tracker.org\/de\/maersk-lavras\/","title":{"rendered":"MAERSK LAVRAS"},"content":{"rendered":"<h2><span style=\"color: #000000;\">Aktueller Standort und <\/span><span style=\"color: #000000;\">Position von MAERSK LAVRAS<\/span><\/h2>\n<p>Wo befindet sich MAERSK LAVRAS derzeit?<br \/>\n<script type=\"text\/javascript\">\n  var width=\"100%\";var height=\"400\";\n  var mmsi=477535200;\n<\/script><script type=\"text\/javascript\" src=\"https:\/\/www.vesselfinder.com\/aismap.js\"><\/script><\/p>\n<p>Die MAERSK LAVRAS, ein Frachtschiff unter der Flagge von Hongkong, ist derzeit auf See unterwegs. Das Schiff mit der IMO-Nummer 9526928 und der MMSI-Nummer 477535200 ist 300 Meter lang und 45 Meter breit. Die unten bereitgestellten Karten enthalten detaillierte Reiseinformationen, darunter den aktuellen Standort des Schiffs, seinen n\u00e4chsten geplanten Anlaufhafen, die voraussichtliche Ankunftszeit (ETA), die voraussichtliche Ankunftszeit (PTA), die Geschwindigkeit, den Kurs und den Tiefgang. Zus\u00e4tzliche Ressourcen wie Fotos, Videos, Ortszeit und UTC-Zeit werden ebenfalls bereitgestellt.<\/p>\n<h2 class=\"pageTitle shipItemTitle\"><span style=\"color: #000000;\">MAERSK LAVRAS Testbericht und Spezifikationen<\/span><\/h2>\n<table>\n<tbody>\n<tr>\n<td style=\"width: 192px;\">Flaggenstaat<\/td>\n<td style=\"width: 192px;\">Hongkong<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Baujahr<strong><br \/>\n<\/strong><\/td>\n<td style=\"width: 192px;\">2011<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Schiffstyp<\/td>\n<td style=\"width: 192px;\">Containerschiff<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Rufzeichen<\/td>\n<td style=\"width: 192px;\">VRJH6<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Bruttoraumzahl<\/td>\n<td style=\"width: 192px;\">89687<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Sommer-Deadweight<\/td>\n<td style=\"width: 192px;\">106043<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">L\u00e4nge<\/td>\n<td style=\"width: 192px;\"><span class=\"specificationUnit\">300 m<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Strahl<\/td>\n<td style=\"width: 192px;\"><span class=\"specificationUnit\">45 m<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Meiner Meinung nach<\/td>\n<td style=\"width: 192px;\">9526928<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">MMSI<\/td>\n<td style=\"width: 192px;\">477535200<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 192px;\">Eigent\u00fcmer<\/td>\n<td style=\"width: 192px;\"><a href=\"https:\/\/ship-tracker.org\/de\/maersk\/\">Maersk<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Aktueller Standort und Position der MAERSK LAVRAS Wo befindet sich die MAERSK LAVRAS derzeit? Die MAERSK LAVRAS, ein unter der Flagge Hongkongs registriertes Frachtschiff, ist derzeit auf See. Das Schiff mit der IMO-Nummer 9526928 und der MMSI-Nummer 477535200 ist 300 Meter lang und 45 Meter breit. Das Schiff\u2026&nbsp;<a href=\"https:\/\/ship-tracker.org\/de\/maersk-lavras\/\" rel=\"bookmark\">Weiterlesen \u00bb<span class=\"screen-reader-text\">MAERSK LAVRAS<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":3637,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"class_list":["post-3948","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MAERSK LAVRAS\u2503Current location and position (cargo ship)<\/title>\n<meta name=\"description\" content=\"MAERSK LAVRAS \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ship-tracker.org\/de\/maersk-lavras\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAERSK LAVRAS\u2503Current location and position (cargo ship)\" \/>\n<meta property=\"og:description\" content=\"MAERSK LAVRAS \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ship-tracker.org\/de\/maersk-lavras\/\" \/>\n<meta property=\"og:site_name\" content=\"Ship-tracker.org\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/\",\"url\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/\",\"name\":\"MAERSK LAVRAS\u2503Current location and position (cargo ship)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ship-tracker.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/maersk-tanjong-g275700498_640.jpg\",\"datePublished\":\"2023-06-21T15:09:55+00:00\",\"description\":\"MAERSK LAVRAS \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ship-tracker.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/maersk-tanjong-g275700498_640.jpg\",\"contentUrl\":\"https:\\\/\\\/ship-tracker.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/maersk-tanjong-g275700498_640.jpg\",\"width\":640,\"height\":446,\"caption\":\"MAERSK ABERDEEN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/maersk-lavras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ship-tracker.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAERSK LAVRAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ship-tracker.org\\\/#website\",\"url\":\"https:\\\/\\\/ship-tracker.org\\\/\",\"name\":\"Ship-tracker.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ship-tracker.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAERSK LAVRAS\u2503Aktueller Standort und Position (Frachtschiff)","description":"MAERSK LAVRAS \u2693 Aktueller Standort und Position des MAERSK-Schiffs \u2713 Maersk-Containerverfolgung \u2713 Live-Schiffstracker \u2713 Containerschiff","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ship-tracker.org\/de\/maersk-lavras\/","og_locale":"de_DE","og_type":"article","og_title":"MAERSK LAVRAS\u2503Current location and position (cargo ship)","og_description":"MAERSK LAVRAS \u2693 Current location and position of MAERSK Vessel \u2713 Maersk container tracking \u2713 Live Ship Tracker \u2713 Container ship","og_url":"https:\/\/ship-tracker.org\/de\/maersk-lavras\/","og_site_name":"Ship-tracker.org","og_image":[{"width":640,"height":446,"url":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ship-tracker.org\/maersk-lavras\/","url":"https:\/\/ship-tracker.org\/maersk-lavras\/","name":"MAERSK LAVRAS\u2503Aktueller Standort und Position (Frachtschiff)","isPartOf":{"@id":"https:\/\/ship-tracker.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ship-tracker.org\/maersk-lavras\/#primaryimage"},"image":{"@id":"https:\/\/ship-tracker.org\/maersk-lavras\/#primaryimage"},"thumbnailUrl":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","datePublished":"2023-06-21T15:09:55+00:00","description":"MAERSK LAVRAS \u2693 Aktueller Standort und Position des MAERSK-Schiffs \u2713 Maersk-Containerverfolgung \u2713 Live-Schiffstracker \u2713 Containerschiff","breadcrumb":{"@id":"https:\/\/ship-tracker.org\/maersk-lavras\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ship-tracker.org\/maersk-lavras\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ship-tracker.org\/maersk-lavras\/#primaryimage","url":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","contentUrl":"https:\/\/ship-tracker.org\/wp-content\/uploads\/2023\/06\/maersk-tanjong-g275700498_640.jpg","width":640,"height":446,"caption":"MAERSK ABERDEEN"},{"@type":"BreadcrumbList","@id":"https:\/\/ship-tracker.org\/maersk-lavras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ship-tracker.org\/"},{"@type":"ListItem","position":2,"name":"MAERSK LAVRAS"}]},{"@type":"WebSite","@id":"https:\/\/ship-tracker.org\/#website","url":"https:\/\/ship-tracker.org\/","name":"Ship-tracker.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ship-tracker.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/pages\/3948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/comments?post=3948"}],"version-history":[{"count":1,"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/pages\/3948\/revisions"}],"predecessor-version":[{"id":3949,"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/pages\/3948\/revisions\/3949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/media\/3637"}],"wp:attachment":[{"href":"https:\/\/ship-tracker.org\/de\/wp-json\/wp\/v2\/media?parent=3948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}